{"id":9686,"date":"2026-05-11T14:11:32","date_gmt":"2026-05-11T14:11:32","guid":{"rendered":"https:\/\/estacionchamamecera.com\/?p=9686"},"modified":"2026-05-11T14:11:32","modified_gmt":"2026-05-11T14:11:32","slug":"actividades-semanales-barrio-el-silbido","status":"publish","type":"post","link":"https:\/\/estacionchamamecera.com\/index.php\/2026\/05\/11\/actividades-semanales-barrio-el-silbido\/","title":{"rendered":"Actividades Semanales \u2013 Barrio El Silbido"},"content":{"rendered":"\r\n<p><img decoding=\"async\" class=\"aligncenter size-medium wp-image-9691\" src=\"http:\/\/estacionchamamecera.com\/wp-content\/uploads\/2026\/05\/688288196_17927372793291315_3558238025906076552_n-240x300.jpg\" alt=\"\" width=\"240\" height=\"300\" srcset=\"https:\/\/estacionchamamecera.com\/wp-content\/uploads\/2026\/05\/688288196_17927372793291315_3558238025906076552_n-240x300.jpg 240w, https:\/\/estacionchamamecera.com\/wp-content\/uploads\/2026\/05\/688288196_17927372793291315_3558238025906076552_n-819x1024.jpg 819w, https:\/\/estacionchamamecera.com\/wp-content\/uploads\/2026\/05\/688288196_17927372793291315_3558238025906076552_n-768x960.jpg 768w, https:\/\/estacionchamamecera.com\/wp-content\/uploads\/2026\/05\/688288196_17927372793291315_3558238025906076552_n-555x694.jpg 555w, https:\/\/estacionchamamecera.com\/wp-content\/uploads\/2026\/05\/688288196_17927372793291315_3558238025906076552_n.jpg 1024w\" sizes=\"(max-width: 240px) 100vw, 240px\" \/>Desde el mes de abril se vienen desarrollando distintas propuestas en el barrio, con el objetivo de generar espacios de encuentro, aprendizaje y recreaci\u00f3n para todas las edades.<br \/>\ud83d\udc83 Talleres de ritmos latinos<br \/>\u2728 Talleres de bisuter\u00eda<br \/>\ud83e\uddd1\u200d\ud83e\udd1d\u200d\ud83e\uddd1 Espacios para adolescentes<br \/>\ud83c\udfc3\u200d\u2642\ufe0f Silbido en Movimiento<br \/>\ud83d\udcda Acompa\u00f1amiento escolar para nivel primario y secundario<br \/>\u26bd Deporte en los barrios + merienda (para ni\u00f1os de 6 a 12 a\u00f1os)<br \/>\ud83e\udd1d Seguimos generando espacios que acompa\u00f1an y fortalecen a nuestra comunidad.<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Desde el mes de abril se vienen desarrollando distintas propuestas en el barrio, con el objetivo de generar espacios de encuentro, aprendizaje y recreaci\u00f3n para todas las edades.\ud83d\udc83 Talleres de ritmos latinos\u2728 Talleres de bisuter\u00eda\ud83e\uddd1\u200d\ud83e\udd1d\u200d\ud83e\uddd1 Espacios para adolescentes\ud83c\udfc3\u200d\u2642\ufe0f Silbido en Movimiento\ud83d\udcda Acompa\u00f1amiento escolar para nivel primario y secundario\u26bd Deporte en los barrios + merienda (para &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/estacionchamamecera.com\/index.php\/2026\/05\/11\/actividades-semanales-barrio-el-silbido\/\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-9686","post","type-post","status-publish","format-standard","hentry","category-locales","item-wrap"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/estacionchamamecera.com\/index.php\/wp-json\/wp\/v2\/posts\/9686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/estacionchamamecera.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/estacionchamamecera.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/estacionchamamecera.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/estacionchamamecera.com\/index.php\/wp-json\/wp\/v2\/comments?post=9686"}],"version-history":[{"count":2,"href":"https:\/\/estacionchamamecera.com\/index.php\/wp-json\/wp\/v2\/posts\/9686\/revisions"}],"predecessor-version":[{"id":9692,"href":"https:\/\/estacionchamamecera.com\/index.php\/wp-json\/wp\/v2\/posts\/9686\/revisions\/9692"}],"wp:attachment":[{"href":"https:\/\/estacionchamamecera.com\/index.php\/wp-json\/wp\/v2\/media?parent=9686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/estacionchamamecera.com\/index.php\/wp-json\/wp\/v2\/categories?post=9686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/estacionchamamecera.com\/index.php\/wp-json\/wp\/v2\/tags?post=9686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}